{"id":17186,"date":"2026-05-13T15:00:08","date_gmt":"2026-05-13T18:00:08","guid":{"rendered":"https:\/\/www.cacauechocolate.com.br\/v1\/?p=17186"},"modified":"2026-05-13T15:19:08","modified_gmt":"2026-05-13T18:19:08","slug":"mel-de-cacau-a-resposta-de-itubera-a-crise-da-lavoura","status":"publish","type":"post","link":"https:\/\/www.cacauechocolate.com.br\/v1\/2026\/05\/13\/mel-de-cacau-a-resposta-de-itubera-a-crise-da-lavoura\/","title":{"rendered":"Mel de Cacau: a  resposta de Ituber\u00e1 \u00e0 crise da lavoura"},"content":{"rendered":"<p>De janeiro a mar\u00e7o de 2026, o pre\u00e7o do cacau caiu 53%, chegando a R$ 165 a saca de 15 kg. Para muitos agricultores do baixo Sul da Bahia, isso significou uma redu\u00e7\u00e3o de at\u00e9 90% na lucratividade. Mas em Ituber\u00e1, a Coopermata &#8211; Cooperativa da Mata Atl\u00e2ntica apostou numa sa\u00edda que n\u00e3o depende da bolsa de commodities: o Mel de Cacau.<\/p>\n<p>L\u00edquido mucilaginoso extra\u00eddo da polpa branca do fruto, o Mel de Cacau \u00e9 100% vegano, tem apelo gastron\u00f4mico crescente e encontra mercado em bares, restaurantes, chefs de cozinha e pousadas da regi\u00e3o e de todo o pa\u00eds. A Coopermata \u00e9 idealizadora do Projeto Pratigi Sustent\u00e1vel, que desde 2025 vem ampliando a produ\u00e7\u00e3o desta iguaria com apoio financeiro da AIP\u00ca, Instituto Votorantim e BNDES.<\/p>\n<p><strong>Equipamentos, fam\u00edlias e quilombolas<\/strong><\/p>\n<figure id=\"attachment_17204\" aria-describedby=\"caption-attachment-17204\" style=\"width: 405px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-17204\" src=\"https:\/\/www.cacauechocolate.com.br\/v1\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-13-12-58-30-1.jpg\" alt=\"\" width=\"405\" height=\"228\" srcset=\"https:\/\/www.cacauechocolate.com.br\/v1\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-13-12-58-30-1.jpg 640w, https:\/\/www.cacauechocolate.com.br\/v1\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-13-12-58-30-1-300x169.jpg 300w, https:\/\/www.cacauechocolate.com.br\/v1\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-13-12-58-30-1-390x220.jpg 390w\" sizes=\"(max-width: 405px) 100vw, 405px\" \/><figcaption id=\"caption-attachment-17204\" class=\"wp-caption-text\">Prensas de inox substituidas pela cooperativa<\/figcaption><\/figure>\n<p>S\u00e3o 40 benefici\u00e1rios diretos, fam\u00edlias atendidas por meio de doa\u00e7\u00f5es, inclusive associa\u00e7\u00f5es e coletivos informais. O projeto distribui freezers de 540 litros e prensas de inox a agricultores familiares de baixa renda e quilombolas substituindo as tradicionais prensas de madeira e avan\u00e7ando na transi\u00e7\u00e3o sanit\u00e1ria da produ\u00e7\u00e3o. A iniciativa segue at\u00e9 2027, com novas entregas de prensas e composteiras para produ\u00e7\u00e3o de h\u00famus de minhoca, importante Bio-Insumo.<\/p>\n<p><strong>Quem conduz<\/strong><\/p>\n<figure id=\"attachment_17188\" aria-describedby=\"caption-attachment-17188\" style=\"width: 314px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-17188\" src=\"https:\/\/www.cacauechocolate.com.br\/v1\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-12-11-56-37-3.jpg\" alt=\"\" width=\"314\" height=\"250\" srcset=\"https:\/\/www.cacauechocolate.com.br\/v1\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-12-11-56-37-3.jpg 589w, https:\/\/www.cacauechocolate.com.br\/v1\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-12-11-56-37-3-300x239.jpg 300w\" sizes=\"(max-width: 314px) 100vw, 314px\" \/><figcaption id=\"caption-attachment-17188\" class=\"wp-caption-text\">As antigas prensas de madeira d\u00e3o lugar a equipamentos modernos<\/figcaption><\/figure>\n<p>A coordena\u00e7\u00e3o t\u00e9cnica \u00e9 da doutora em Gen\u00e9tica e engenheira agr\u00f4noma D\u2019avila Maria Ara\u00fajo:\u00a0<em>\u201cCada entrega \u00e9 um misto de sentimentos. Saber que os produtores podem vender para bares, restaurantes e pousadas nos inspira \u2014 e inspira\u00e7\u00e3o \u00e9 o que n\u00e3o falta.\u201d<\/em><\/p>\n<p>Josu\u00e9 Castro, diretor executivo da Coopermata, destaca que a cooperativa j\u00e1 conta com emp\u00f3rio pr\u00f3prio, marca de chocolate fino bean to bar (PRATIGI), linha de microcr\u00e9dito e pesquisa de patente para ampliar a conserva\u00e7\u00e3o do produto, hoje vendido apenas congelado por seu car\u00e1ter perec\u00edvel.<\/p>\n<p><strong>Um sonho com escala<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17189\" src=\"https:\/\/www.cacauechocolate.com.br\/v1\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-12-11-56-37.jpg\" alt=\"\" width=\"329\" height=\"308\" srcset=\"https:\/\/www.cacauechocolate.com.br\/v1\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-12-11-56-37.jpg 425w, https:\/\/www.cacauechocolate.com.br\/v1\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-12-11-56-37-300x281.jpg 300w\" sizes=\"(max-width: 329px) 100vw, 329px\" \/><\/p>\n<p>A consultora ambiental do projeto, Jurema Cintra, autora do poema <em>Ode ao Mel de Cacau<\/em> (2019), sintetiza a ambi\u00e7\u00e3o: \u201cDesejamos que Itubera\u0301 se torne a maior produtora de Mel de Cacau do Brasil e do mundo, exportando e garantindo qualidade de vida para homens e mulheres campesinas.\u201d<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17190\" src=\"https:\/\/www.cacauechocolate.com.br\/v1\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-12-11-56-37-2.jpg\" alt=\"\" width=\"275\" height=\"313\" srcset=\"https:\/\/www.cacauechocolate.com.br\/v1\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-12-11-56-37-2.jpg 440w, https:\/\/www.cacauechocolate.com.br\/v1\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-12-11-56-37-2-263x300.jpg 263w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/><\/p>\n<p><strong>FICHA DO PROJETO<\/strong><\/p>\n<p><strong>Cooperativa: <\/strong>Coopermata \u2014 Cooperativa da Mata Atl\u00e2ntica<\/p>\n<p><strong>Projeto: <\/strong>Pratigi Sustent\u00e1vel<\/p>\n<p><strong>Localiza\u00e7\u00e3o: <\/strong>Ituber\u00e1 e microrregi\u00e3o, baixo Sul da Bahia<\/p>\n<p><strong>Apoiadores: <\/strong>AIP\u00ca, Instituto Votorantim, Heinecken, BNDES<\/p>\n<p><strong>Benefici\u00e1rios: <\/strong>40+ individuais \u00b7 100+ fam\u00edlias \u00b7 comunidades quilombolas<\/p>\n<p><strong>Vig\u00eancia: <\/strong>At\u00e9 2027<\/p>\n<p><strong>Produto: <\/strong>Mel de Cacau \u2014 100% vegano, mercado gastron\u00f4mico<\/p>\n<p><strong>Contato: <\/strong>Coopermata \/ @coopermata<\/p>\n<p>Fone\u00a0 73-991128849<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De janeiro a mar\u00e7o de 2026, o pre\u00e7o do cacau caiu 53%, chegando a R$ 165 a saca de 15 kg. Para muitos agricultores do baixo Sul da Bahia, isso significou uma redu\u00e7\u00e3o de at\u00e9 90% na lucratividade. Mas em Ituber\u00e1, a Coopermata &#8211; Cooperativa da Mata Atl\u00e2ntica apostou numa sa\u00edda que n\u00e3o depende da &hellip;<\/p>\n","protected":false},"author":2,"featured_media":17187,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3,1],"tags":[3976,285,476,6],"class_list":["post-17186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-geral","tag-coopermata-cooperativa-da-mata-atlantica","tag-itubera","tag-mel-de-cacau","tag-sul-da-bahia"],"views":45,"_links":{"self":[{"href":"https:\/\/www.cacauechocolate.com.br\/v1\/wp-json\/wp\/v2\/posts\/17186"}],"collection":[{"href":"https:\/\/www.cacauechocolate.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cacauechocolate.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cacauechocolate.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cacauechocolate.com.br\/v1\/wp-json\/wp\/v2\/comments?post=17186"}],"version-history":[{"count":4,"href":"https:\/\/www.cacauechocolate.com.br\/v1\/wp-json\/wp\/v2\/posts\/17186\/revisions"}],"predecessor-version":[{"id":17205,"href":"https:\/\/www.cacauechocolate.com.br\/v1\/wp-json\/wp\/v2\/posts\/17186\/revisions\/17205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cacauechocolate.com.br\/v1\/wp-json\/wp\/v2\/media\/17187"}],"wp:attachment":[{"href":"https:\/\/www.cacauechocolate.com.br\/v1\/wp-json\/wp\/v2\/media?parent=17186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cacauechocolate.com.br\/v1\/wp-json\/wp\/v2\/categories?post=17186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cacauechocolate.com.br\/v1\/wp-json\/wp\/v2\/tags?post=17186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}